{"id":6539,"date":"2021-07-12T11:24:50","date_gmt":"2021-07-12T09:24:50","guid":{"rendered":"https:\/\/gauthierdupertuis.com\/?page_id=6539"},"modified":"2026-02-25T02:51:31","modified_gmt":"2026-02-25T00:51:31","slug":"postcards-from-tomorrow-cb","status":"publish","type":"page","link":"https:\/\/gauthierdupertuis.com\/de\/postcards-from-tomorrow-cb\/","title":{"rendered":"Postcards from tomorrow"},"content":{"rendered":"<div data-colibri-id=\"6539-c1\" class=\"style-2593 style-local-6539-c1 position-relative\">\r\n  <div class=\"background-wrapper\">\r\n    <div class=\"background-layer background-layer-media-container-lg\">\r\n      <!---->\r\n      <div class=\"overlay-layer\">\r\n        <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.7;\"><\/div>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"background-layer background-layer-media-container-md\">\r\n      <!---->\r\n      <div class=\"overlay-layer\">\r\n        <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.7;\"><\/div>\r\n      <\/div>\r\n    <\/div>\r\n    <div class=\"background-layer background-layer-media-container\">\r\n      <!---->\r\n      <div class=\"overlay-layer\">\r\n        <div class=\"overlay-image-layer\" style=\"background-color: rgb(0, 0, 0); opacity: 0.7;\"><\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n  <div data-colibri-component=\"section\" data-colibri-id=\"6539-c2\" id=\"custom\" class=\"h-section h-section-global-spacing d-flex align-items-lg-center align-items-md-center align-items-center style-2594 style-local-6539-c2 position-relative\">\r\n    <!---->\r\n    <!---->\r\n    <div class=\"h-section-grid-container h-section-boxed-container\">\r\n      <!---->\r\n      <div data-colibri-id=\"6539-c3\" class=\"h-row-container gutters-row-lg-0 gutters-row-md-0 gutters-row-0 gutters-row-v-lg-0 gutters-row-v-md-0 gutters-row-v-0 style-2595 style-local-6539-c3 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-0 gutters-col-md-0 gutters-col-0 gutters-col-v-lg-0 gutters-col-v-md-0 gutters-col-v-0\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2596-outer style-local-6539-c4-outer\">\r\n            <div data-colibri-id=\"6539-c4\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-0 h-px-md-0 h-px-0 v-inner-lg-0 v-inner-md-0 v-inner-0 style-2596 style-local-6539-c4 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-center align-self-md-center align-self-center\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c5\" class=\"page-title style-2597 style-local-6539-c5 position-relative h-element\">\r\n                  <!---->\r\n                  <div class=\"h-page-title__outer style-2597-outer style-local-6539-c5-outer\">\r\n                    <div class=\"h-global-transition-all\"><span><h1 style='margin-bottom:0'>Postcards from tomorrow<\/h1><\/span><\/div>\r\n                  <\/div>\r\n                <\/div>\r\n                <div data-colibri-id=\"6539-c6\" class=\"h-text h-text-component style-2598 style-local-6539-c6 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <p>f\u00fcr Blasorchester<\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c7\" class=\"h-row-container gutters-row-lg-0 gutters-row-md-0 gutters-row-0 gutters-row-v-lg-0 gutters-row-v-md-0 gutters-row-v-0 style-2595 style-local-6539-c7 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-0 gutters-col-md-0 gutters-col-0 gutters-col-v-lg-0 gutters-col-v-md-0 gutters-col-v-0\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg h-col-md h-col-auto style-2596-outer style-local-6539-c8-outer\">\r\n            <div data-colibri-id=\"6539-c8\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-0 h-px-md-0 h-px-0 v-inner-lg-0 v-inner-md-0 v-inner-0 style-2596 style-local-6539-c8 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-center align-self-md-center align-self-center\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c9\" class=\"style-2599 style-local-6539-c9 position-relative h-element\">\r\n                  <!---->\r\n                  <div class=\"\"><div class=\"_df_book df-lite\" id=\"df_6796\"  _slug=\"6796\" data-title=\"postcards-from-tomorrow-cb\" wpoptions=\"true\" thumbtype=\"\" ><\/div><script class=\"df-shortcode-script\" nowprocket type=\"application\/javascript\">window.option_df_6796 = {\"outline\":[],\"autoEnableOutline\":\"false\",\"autoEnableThumbnail\":\"false\",\"overwritePDFOutline\":\"false\",\"enableDownload\":\"false\",\"direction\":\"1\",\"pageSize\":\"0\",\"soundEnable\":\"false\",\"source\":\"https:\\\/\\\/gauthierdupertuis.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/00-Postcards-from-tomorrow-CB-Score-4.pdf\",\"wpOptions\":\"true\"}; if(window.DFLIP && window.DFLIP.parseBooks){window.DFLIP.parseBooks();}<\/script><\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c10\" class=\"h-row-container gutters-row-lg-1 gutters-row-md-1 gutters-row-0 gutters-row-v-lg-1 gutters-row-v-md-1 gutters-row-v-1 style-2600 style-local-6539-c10 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-1 gutters-col-md-1 gutters-col-0 gutters-col-v-lg-1 gutters-col-v-md-1 gutters-col-v-1\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2601-outer style-local-6539-c11-outer\">\r\n            <div data-colibri-id=\"6539-c11\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-0 h-px-md-0 h-px-0 v-inner-lg-0 v-inner-md-0 v-inner-0 style-2601 style-local-6539-c11 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c12\" class=\"style-2599 style-local-6539-c12 position-relative h-element\">\r\n                  <!---->\r\n                  <div class=\"\"><iframe loading=\"lazy\" width=\"100%\" height=\"20\" scrolling=\"no\" frameborder=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/soundcloud%253Atracks%253A1224577714&color=%23333333&inverse=true&auto_play=false&show_user=true\"><\/iframe><\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c13\" class=\"h-row-container gutters-row-lg-0 gutters-row-md-0 gutters-row-0 gutters-row-v-lg-0 gutters-row-v-md-0 gutters-row-v-0 style-2602 style-local-6539-c13 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-0 gutters-col-md-0 gutters-col-0 gutters-col-v-lg-0 gutters-col-v-md-0 gutters-col-v-0\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2603-outer style-local-6539-c14-outer\">\r\n            <div data-colibri-id=\"6539-c14\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-0 h-px-md-0 h-px-0 v-inner-lg-0 v-inner-md-0 v-inner-0 style-2603 style-local-6539-c14 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c15\" class=\"h-text h-text-component style-2604 style-local-6539-c15 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <p>Sinfonische Dichtung \u2022 2021\r\n                      <br>Schwierigkeitsgrad 2.5 (leicht) \u2022 07:00 \u2022  FC Music Publishing<em style=\"font-size: 14px;\"><br>Auch f\u00fcr <\/em>\r\n                      <a href=\"https:\/\/gauthierdupertuis.com\/de\/music\/postcards-from-tomorrow-bb\/\" style=\"font-size: 14px; font-weight: 600;\"><em>Brass Band<\/em><\/a><em style=\"font-size: 14px;\">.<\/em><\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c16\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2605 style-local-6539-c16 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2606-outer style-local-6539-c17-outer\">\r\n            <div data-colibri-id=\"6539-c17\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2606 style-local-6539-c17 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c18\" class=\"h-x-container style-2607 style-local-6539-c18 position-relative h-element\">\r\n                  <!---->\r\n                  <div class=\"h-x-container-inner style-dynamic-6539-c18-group style-2607-spacing style-local-6539-c18-spacing\"><span class=\"h-button__outer style-2608-outer style-local-6539-c19-outer d-inline-flex h-element\"><a h-use-smooth-scroll=\"true\" href=\"https:\/\/www.bandmusicshop.com\/postcards-from-tomorrow-fcmp012--sc?returnurl=%2fsearch%3fq%3dgauthier%2bdupertuis%26substoreid%3d\" target=\"_blank\"  data-colibri-id=\"6539-c19\" class=\"d-flex w-100 align-items-center h-button justify-content-lg-center justify-content-md-center justify-content-center style-2608 style-local-6539-c19 position-relative\"><!----><span  class=\"h-svg-icon h-button__icon style-2608-icon style-local-6539-c19-icon\"><!--Icon by Font Awesome (https:\/\/fontawesome.com)-->\r\n    <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"shopping-cart\" viewbox=\"0 0 1664 1896.0833\">\r\n      <path d=\"M640 1536q0 52-38 90t-90 38-90-38-38-90 38-90 90-38 90 38 38 90zm896 0q0 52-38 90t-90 38-90-38-38-90 38-90 90-38 90 38 38 90zm128-1088v512q0 24-16.5 42.5T1607 1024L563 1146q13 60 13 70 0 16-24 64h920q26 0 45 19t19 45-19 45-45 19H448q-26 0-45-19t-19-45q0-11 8-31.5t16-36 21.5-40T445 1207L268 384H64q-26 0-45-19T0 320t19-45 45-19h256q16 0 28.5 6.5T368 278t13 24.5 8 26 5.5 29.5 4.5 26h1201q26 0 45 19t19 45z\"><\/path>\r\n    <\/svg><\/span> <span>Partitur<\/span><\/a>\r\n                    <\/span><span class=\"h-button__outer style-2608-outer style-local-6539-c20-outer d-inline-flex h-element\"><a h-use-smooth-scroll=\"true\" href=\"https:\/\/www.bandmusicshop.com\/postcards-from-tomorrow-fcmp012--cbha?returnurl=%2fsearch%3fq%3dgauthier%2bdupertuis%26substoreid%3d\" target=\"_blank\"  data-colibri-id=\"6539-c20\" class=\"d-flex w-100 align-items-center h-button justify-content-lg-center justify-content-md-center justify-content-center style-2608 style-local-6539-c20 position-relative\"><!----><span  class=\"h-svg-icon h-button__icon style-2608-icon style-local-6539-c20-icon\"><!--Icon by Font Awesome (https:\/\/fontawesome.com)-->\r\n    <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"shopping-cart\" viewbox=\"0 0 1664 1896.0833\">\r\n      <path d=\"M640 1536q0 52-38 90t-90 38-90-38-38-90 38-90 90-38 90 38 38 90zm896 0q0 52-38 90t-90 38-90-38-38-90 38-90 90-38 90 38 38 90zm128-1088v512q0 24-16.5 42.5T1607 1024L563 1146q13 60 13 70 0 16-24 64h920q26 0 45 19t19 45-19 45-45 19H448q-26 0-45-19t-19-45q0-11 8-31.5t16-36 21.5-40T445 1207L268 384H64q-26 0-45-19T0 320t19-45 45-19h256q16 0 28.5 6.5T368 278t13 24.5 8 26 5.5 29.5 4.5 26h1201q26 0 45 19t19 45z\"><\/path>\r\n    <\/svg><\/span> <span>Kompletter Satz<\/span><\/a>\r\n                    <\/span>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c21\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2609 style-local-6539-c21 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2610-outer style-local-6539-c22-outer\">\r\n            <div data-colibri-id=\"6539-c22\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2610 style-local-6539-c22 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c23\" class=\"h-text h-text-component style-2611 style-local-6539-c23 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <p><strong>Instrumentation :<\/strong> Picc(opt), 2Fl(2.opt), Ob, Bsn(opt), EbCl(opt), 3Cl(3.opt), BCl(opt), 2ASax, TSax, BSax(opt), 3Tpt(3.opt), 2Hn, 3Tbn(3.opt), Euph, Tba, DBs(opt), 4Perc(3.opt)<\/p>\r\n                  <\/div>\r\n                <\/div>\r\n                <div data-colibri-id=\"6539-c24\" class=\"h-text h-text-component style-2611 style-local-6539-c24 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <p class=\"translation-block\">Beim Schreiben von <em>Postkarten von morgen <\/em> lie\u00df ich mich von einer Tradition inspirieren, die ich poetisch finde: Manche Kinder vergraben eine Schachtel im Garten mit Spielzeug, Zeichnungen, in den sie ihre W\u00fcnsche f\u00fcr ihre Zukunft illustrieren, und die sie als Erwachsene ausgraben werden. Damit wollte ich die poetische Interpretation dieser Tradition erweitern: was w\u00fcnschen wir uns f\u00fcr die Zukunft, welche Postkarten m\u00f6chten wir unseren Enkeln schreiben?<\/p>\r\n                    <p>Ich habe dieses St\u00fcck in drei <em>attaca<\/em> gespielten S\u00e4tzen geschrieben - jeder Satz repr\u00e4sentiert eine Postkarte mit symbolischer Bedeutung.<\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c25\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2612 style-local-6539-c25 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2613-outer style-local-6539-c26-outer\">\r\n            <div data-colibri-id=\"6539-c26\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2613 style-local-6539-c26 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c27\" class=\"h-text h-text-component style-2614 style-local-6539-c27 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <h4><span style=\"color: rgb(255, 255, 255); font-family: Montserrat;\">I. Abandoned Blockhouses&nbsp;<\/span><\/h4>\r\n                    <p><em style=\"color: rgb(255, 255, 255); font-family: Montserrat;\">(Verlassene Blockh\u00e4user)<\/em><\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c28\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2615 style-local-6539-c28 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2616-outer style-local-6539-c29-outer\">\r\n            <div data-colibri-id=\"6539-c29\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2616 style-local-6539-c29 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-center align-self-md-center align-self-center\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c30\" class=\"d-block style-2617 style-local-6539-c30 position-relative h-element\">\r\n                  <!---->\r\n                  <div class=\"h-image__frame-container-outer\">\r\n                    <a href=\"https:\/\/www.neverends.net\/blockhaus-du-debarquement-de-normandie\/\" target=\"_blank\" h-use-smooth-scroll=\"true\" class=\"image-link\">\r\n                      <div class=\"h-image__frame-container\">\r\n                        <!---->\r\n                        <!---->\r\n                        <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" data-attachment-id=\"6757\" data-permalink=\"https:\/\/gauthierdupertuis.com\/de\/olympus-digital-camera\/\" data-orig-file=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/P5270229.jpg\" data-orig-size=\"1000,563\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;E-M5MarkII&quot;,&quot;caption&quot;:&quot;OLYMPUS DIGITAL CAMERA&quot;,&quot;created_timestamp&quot;:&quot;1495878354&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;OLYMPUS DIGITAL CAMERA&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"OLYMPUS DIGITAL CAMERA\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Source : neverends.net&lt;\/p&gt;\" data-large-file=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/P5270229.jpg\" src=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/P5270229.jpg\" class=\"wp-image-6757 style-2617-image style-local-6539-c30-image\" alt=\"\" srcset=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/P5270229.jpg 1000w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/P5270229-300x169.jpg 300w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/P5270229-768x432.jpg 768w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/P5270229-18x10.jpg 18w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/P5270229-600x338.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\r\n                        <div class=\"h-image__frame h-hide-lg h-hide-md h-hide-sm style-2617-frameImage style-local-6539-c30-frameImage\"><\/div>\r\n                      <\/div>\r\n                      <div class=\"style-2617-caption style-local-6539-c30-caption\">\r\n                        Quelle : neverends.net\r\n                      <\/div>\r\n                    <\/a>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2618-outer style-local-6539-c31-outer\">\r\n            <div data-colibri-id=\"6539-c31\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2618 style-local-6539-c31 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-center align-self-md-center align-self-center\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c32\" class=\"h-text h-text-component style-2611 style-local-6539-c32 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <p>Le titre du premier mouvement fait r\u00e9f\u00e9rence \u00e0 la guerre et \u00e0 la capacit\u00e9 de destruction de l&rsquo;humanit\u00e9. A une \u00e9poque o\u00f9 les d\u00e9fis socio-politiques et environnementaux sont aussi importants, il est primordial que nous n&rsquo;oubliions pas\r\n                      les horreurs du pass\u00e9 : comme des blockhaus abandonn\u00e9s, les reliques de nos horreurs resteront pour longtemps. Mais il faut avancer.<\/p>\r\n                    <p class=\"translation-block\">Der Satz beginnt mit einer Passage mit zuf\u00e4llige Musik. Das Thema der Erde, das das ganze St\u00fcck durchziehen wird, wird dort ab dem f\u00fcnften Takt gespielt. Das Thema entwickelt sich dann zu einem Schrei der Verzweiflung in d-Moll (Buchstabe A), vor einem Abschnitt, der die Schrecken des Krieges darstellt, dargestellt durch aggressive Muster auf Schlagzeug und tiefe Blechbl\u00e4sern. Das von den Holzbl\u00e4sern und dem Vibraphon gespielte  <em>ostinato<\/em>-Motiv verk\u00fcndet der letzte Abschnitt: eine Fanfare nach dem gregorianischen <em> Dies Irae <\/em>, dessen Text den Tag des g\u00f6ttlichen Zorns ank\u00fcndigt, der aber vor allem eine Bitte um Vergebung f\u00fcr unsere S\u00fcnden ist.<\/p>\r\n                    <p>\r\n                      <br>\r\n                    <\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c33\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2619 style-local-6539-c33 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2620-outer style-local-6539-c34-outer\">\r\n            <div data-colibri-id=\"6539-c34\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2620 style-local-6539-c34 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c35\" class=\"h-text h-text-component style-2614 style-local-6539-c35 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <h4><span style=\"color: rgb(255, 255, 255); font-family: Montserrat;\">II. Pagoda at the Lake&nbsp;<\/span><\/h4>\r\n                    <p><em style=\"color: rgb(255, 255, 255); font-family: Montserrat;\">(Die Pagode am See)<\/em><\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c36\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2615 style-local-6539-c36 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2618-outer style-local-6539-c37-outer\">\r\n            <div data-colibri-id=\"6539-c37\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2618 style-local-6539-c37 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-center align-self-md-center align-self-center\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c38\" class=\"h-text h-text-component style-2611 style-local-6539-c38 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <p>Le deuxi\u00e8me mouvement s&rsquo;inspi\u00e8re de la pagode, monument religieux abritant les reliques de personnages sacr\u00e9es dans certains cultes asiatiques. Ceci pourrait ainsi symboliser le fait que l&rsquo;humanit\u00e9, pour pouvoir faire face aux d\u00e9fis\r\n                      auxquels elle est confront\u00e9e, pourrait avoir besoin de rechercher ses racines et de se poser la question des choses importantes dans son histoire.<\/p>\r\n                    <p>Ce mouvement se veut calme et apais\u00e9 : il est ainsi constitu\u00e9 d&rsquo;un mat\u00e9riau musical simple et met en \u00e9vidence certains solistes de l&rsquo;ensemble. Il suit en outre une structure en arche (ABCBA), rappelant l&rsquo;architecture harmonieuse de\r\n                      la pagode.<\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2616-outer style-local-6539-c39-outer\">\r\n            <div data-colibri-id=\"6539-c39\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2616 style-local-6539-c39 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-center align-self-md-center align-self-center\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c40\" class=\"d-block style-2617 style-local-6539-c40 position-relative h-element\">\r\n                  <!---->\r\n                  <div class=\"h-image__frame-container-outer\">\r\n                    <div class=\"h-image__frame-container\">\r\n                      <!---->\r\n                      <!---->\r\n                      <img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"1300\" data-attachment-id=\"6779\" data-permalink=\"https:\/\/gauthierdupertuis.com\/de\/pexels-photo-1643130\/\" data-orig-file=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130.jpeg\" data-orig-size=\"980,1300\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pexels-photo-1643130\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Source : &lt;\/p&gt;\" data-large-file=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130-772x1024.jpeg\" src=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130.jpeg\" class=\"wp-image-6779 style-2617-image style-local-6539-c40-image\" alt=\"\" srcset=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130.jpeg 980w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130-226x300.jpeg 226w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130-772x1024.jpeg 772w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130-768x1019.jpeg 768w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130-9x12.jpeg 9w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130-150x200.jpeg?crop=1 150w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-1643130-600x796.jpeg 600w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/>\r\n                      <div class=\"h-image__frame h-hide-lg h-hide-md h-hide-sm style-2617-frameImage style-local-6539-c40-frameImage\"><\/div>\r\n                    <\/div>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c41\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2621 style-local-6539-c41 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2622-outer style-local-6539-c42-outer\">\r\n            <div data-colibri-id=\"6539-c42\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2622 style-local-6539-c42 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c43\" class=\"h-text h-text-component style-2614 style-local-6539-c43 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <h4><span style=\"color: rgb(255, 255, 255); font-family: Montserrat;\">III. Building Bridges&nbsp;<\/span><\/h4>\r\n                    <p><em style=\"color: rgb(255, 255, 255); font-family: Montserrat;\">(Construire des ponts)<\/em><\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c44\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2615 style-local-6539-c44 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2616-outer style-local-6539-c45-outer\">\r\n            <div data-colibri-id=\"6539-c45\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2616 style-local-6539-c45 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-center align-self-md-center align-self-center\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c46\" class=\"d-block style-2617 style-local-6539-c46 position-relative h-element\">\r\n                  <!---->\r\n                  <div class=\"h-image__frame-container-outer\">\r\n                    <div class=\"h-image__frame-container\">\r\n                      <!---->\r\n                      <!---->\r\n                      <img loading=\"lazy\" decoding=\"async\" width=\"3780\" height=\"2126\" data-attachment-id=\"6780\" data-permalink=\"https:\/\/gauthierdupertuis.com\/de\/pexels-photo-220762\/\" data-orig-file=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762.jpeg\" data-orig-size=\"3780,2126\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pexels-photo-220762\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-1024x576.jpeg\" src=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762.jpeg\" class=\"wp-image-6780 style-2617-image style-local-6539-c46-image\" alt=\"\" srcset=\"https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762.jpeg 3780w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-300x169.jpeg 300w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-1024x576.jpeg 1024w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-768x432.jpeg 768w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-1536x864.jpeg 1536w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-2048x1152.jpeg 2048w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-18x10.jpeg 18w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-1200x675.jpeg 1200w, https:\/\/gauthierdupertuis.com\/wp-content\/uploads\/2021\/08\/pexels-photo-220762-600x337.jpeg 600w\" sizes=\"auto, (max-width: 3780px) 100vw, 3780px\" \/>\r\n                      <div class=\"h-image__frame h-hide-lg h-hide-md h-hide-sm style-2617-frameImage style-local-6539-c46-frameImage\"><\/div>\r\n                    <\/div>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2618-outer style-local-6539-c47-outer\">\r\n            <div data-colibri-id=\"6539-c47\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2618 style-local-6539-c47 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-center align-self-md-center align-self-center\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c48\" class=\"h-text h-text-component style-2611 style-local-6539-c48 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <p class=\"translation-block\">Der dritte und letzte Satz ist ein Aufruf zur Hoffnung. Sobald wir uns an unsere Vergangenheit erinnern, ist es an der Zeit, uns globalen Herausforderungen zu stellen und die Br\u00fccken zu bauen, die uns zu einer besseren Welt f\u00fchren. Das sind Postkarten die ich gerne unseren Enkeln schicken m\u00f6chte (<em> Postcards for tomorrow <\/em>), aber vor allem bin ich \u00fcberzeugt, dass dies die Postkarten sind, die k\u00fcnftige Generationen erhalten m\u00f6chten (<em>Postcards from tomorrow <\/em>).<\/p>\r\n                    <p>L&rsquo;ostinato de vibraphone et le motif rythmique expos\u00e9 d\u00e8s les spremi\u00e8res mesures servent de \u00ab\u00a0pont\u00a0\u00bb entre les diff\u00e9rentes sections du mouvement, impliquant une forme rondo \u00e9voluant au fil des r\u00e9p\u00e9titions. Les deux premi\u00e8res sections\r\n                      reprennent le mat\u00e9riau musical des mouvements pr\u00e9c\u00e9dents et conduisent \u00e0 une derni\u00e8re r\u00e9p\u00e9tition du pont, plus funky, avant un final h\u00e9ro\u00efque.&nbsp;<\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <div data-colibri-id=\"6539-c49\" class=\"h-row-container gutters-row-lg-2 gutters-row-md-2 gutters-row-0 gutters-row-v-lg-2 gutters-row-v-md-2 gutters-row-v-2 style-2623 style-local-6539-c49 position-relative\">\r\n        <!---->\r\n        <div class=\"h-row justify-content-lg-center justify-content-md-center justify-content-center align-items-lg-stretch align-items-md-stretch align-items-stretch gutters-col-lg-2 gutters-col-md-2 gutters-col-0 gutters-col-v-lg-2 gutters-col-v-md-2 gutters-col-v-2\">\r\n          <!---->\r\n          <div class=\"h-column h-column-container d-flex h-col-lg-auto h-col-md-auto h-col-auto style-2624-outer style-local-6539-c50-outer\">\r\n            <div data-colibri-id=\"6539-c50\" class=\"d-flex h-flex-basis h-column__inner h-px-lg-2 h-px-md-2 h-px-2 v-inner-lg-2 v-inner-md-2 v-inner-2 style-2624 style-local-6539-c50 position-relative\">\r\n              <!---->\r\n              <!---->\r\n              <div class=\"w-100 h-y-container h-column__content h-column__v-align flex-basis-100 align-self-lg-start align-self-md-start align-self-start\">\r\n                <!---->\r\n                <div data-colibri-id=\"6539-c51\" class=\"h-text h-text-component style-2611 style-local-6539-c51 position-relative h-element\">\r\n                  <!---->\r\n                  <!---->\r\n                  <div class=\"\">\r\n                    <p><span style=\"font-weight: 300; font-size: 16px; font-family: Montserrat; color: rgb(255, 255, 255);\">Im Juli 2021 gewann dieses St\u00fcck den ersten Preis beim Kompositionswettbewerb \u201eLa Bacchetta d'Oro\u201c.<\/span><\/p>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>pour orchestre d&rsquo;harmonie Po\u00e8me symphonique \u2022 2021 Difficult\u00e9 2.5 (facile) \u2022 07:00 \u2022 FC Music PublishingCette oeuvre existe \u00e9galement en version Brass Band. Score Set complet Instrumentation : Picc(opt), 2Fl(2.opt), Ob, Bsn(opt), EbCl(opt), 3Cl(3.opt), BCl(opt), 2ASax, TSax, BSax(opt), 3Tpt(3.opt), 2Hn, 3Tbn(3.opt), Euph, Tba, DBs(opt), 4Perc(3.opt) Pour composer Postcards from tomorrow, j\u2019ai \u00e9t\u00e9 inspir\u00e9 d\u2019une tradition [&hellip;]<\/p>\n","protected":false},"author":178170578,"featured_media":6537,"parent":0,"menu_order":-1,"comment_status":"closed","ping_status":"closed","template":"page-templates\/full-width-page.php","meta":{"footnotes":""},"class_list":["post-6539","page","type-page","status-publish","has-post-thumbnail","hentry"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PbAZ0d-1Ht","_links":{"self":[{"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/pages\/6539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/users\/178170578"}],"replies":[{"embeddable":true,"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/comments?post=6539"}],"version-history":[{"count":21,"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/pages\/6539\/revisions"}],"predecessor-version":[{"id":22246,"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/pages\/6539\/revisions\/22246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/media\/6537"}],"wp:attachment":[{"href":"https:\/\/gauthierdupertuis.com\/de\/wp-json\/wp\/v2\/media?parent=6539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}